{"id":21435,"date":"2021-02-25T14:01:53","date_gmt":"2021-02-25T12:01:53","guid":{"rendered":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/"},"modified":"2021-02-25T14:01:53","modified_gmt":"2021-02-25T12:01:53","slug":"gp-ga-44fii","status":"publish","type":"product","link":"https:\/\/maqcenter.com\/pt-pt\/producto\/gp-ga-44fii\/","title":{"rendered":"GP\/GA-44FII"},"content":{"rendered":"<p>Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora cil\u00edndrica para v\u00e1rias opera\u00e7\u00f5es de retifica\u00e7\u00e3o, como: trabalho central, retifica\u00e7\u00e3o de imers\u00e3o direta ou multi-mergulho, retifica\u00e7\u00e3o transversal cil\u00edndrica ou retifica\u00e7\u00e3o transversal c\u00f4nica. <\/p>\n<p>A tecnologia mecatr\u00f4nica de ponta da Okuma para uma ampla variedade de geometrias, mas com opera\u00e7\u00e3o menos intensiva em habilidades, gra\u00e7as aos recursos de programa\u00e7\u00e3o assistida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora cil\u00edndrica para v\u00e1rias opera\u00e7\u00f5es de retifica\u00e7\u00e3o, como: trabalho central, retifica\u00e7\u00e3o de imers\u00e3o direta ou multi-mergulho, retifica\u00e7\u00e3o transversal cil\u00edndrica ou retifica\u00e7\u00e3o transversal c\u00f4nica. A tecnologia mecatr\u00f4nica de ponta da Okuma para uma ampla variedade [&hellip;]<\/p>\n","protected":false},"featured_media":21436,"template":"","meta":[],"product_brand":[],"product_cat":[535,537],"product_tag":[568,569,572,573],"marca-producto":[26],"serie-producto":[292],"class_list":["post-21435","product","type-product","status-publish","has-post-thumbnail","product_cat-retificadoras","product_cat-retificadoras-externas","product_tag-aeronautica-pt-pt","product_tag-automovel","product_tag-ferrovia","product_tag-grande-consumo","marca-producto-okuma","serie-producto-gp-ga-fii","first","instock","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GP\/GA-44FII<\/title>\n<meta name=\"description\" content=\"GP\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GP\/GA-44FII\" \/>\n<meta property=\"og:description\" content=\"GP\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/\" \/>\n<meta property=\"og:site_name\" content=\"MAQcenter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/\",\"url\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/\",\"name\":\"GP\\\/GA-44FII\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maqcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/OKUMA-GP-44FII.jpg\",\"datePublished\":\"2021-02-25T12:01:53+00:00\",\"description\":\"GP\\\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maqcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/OKUMA-GP-44FII.jpg\",\"contentUrl\":\"https:\\\/\\\/maqcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/OKUMA-GP-44FII.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maqcenter.com\\\/producto\\\/gp-ga-44fii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/maqcenter.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/maqcenter.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GP\\\/GA-44FII\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#website\",\"url\":\"https:\\\/\\\/maqcenter.com\\\/\",\"name\":\"MAQcenter\",\"description\":\"El centro de tus soluciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maqcenter.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#organization\",\"name\":\"MAQcenter S.A.\",\"url\":\"https:\\\/\\\/maqcenter.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maqcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/MAQcenter_logo_vertical.svg\",\"contentUrl\":\"https:\\\/\\\/maqcenter.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/MAQcenter_logo_vertical.svg\",\"width\":300,\"height\":174,\"caption\":\"MAQcenter S.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/maqcenter.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GP\/GA-44FII","description":"GP\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/","og_locale":"pt_PT","og_type":"article","og_title":"GP\/GA-44FII","og_description":"GP\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora","og_url":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/","og_site_name":"MAQcenter","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/","url":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/","name":"GP\/GA-44FII","isPartOf":{"@id":"https:\/\/maqcenter.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/#primaryimage"},"image":{"@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/#primaryimage"},"thumbnailUrl":"https:\/\/maqcenter.com\/wp-content\/uploads\/2021\/02\/OKUMA-GP-44FII.jpg","datePublished":"2021-02-25T12:01:53+00:00","description":"GP\/GA-44FII. Esta retificadora de furos de alta precis\u00e3o economiza m\u00e3o de obra devido \u00e0 sua capacidade multi-operacional e facilidade de uso. Uma retificadora","breadcrumb":{"@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/#primaryimage","url":"https:\/\/maqcenter.com\/wp-content\/uploads\/2021\/02\/OKUMA-GP-44FII.jpg","contentUrl":"https:\/\/maqcenter.com\/wp-content\/uploads\/2021\/02\/OKUMA-GP-44FII.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/maqcenter.com\/producto\/gp-ga-44fii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Productos","item":"https:\/\/maqcenter.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/maqcenter.com\/shop\/"},{"@type":"ListItem","position":3,"name":"GP\/GA-44FII"}]},{"@type":"WebSite","@id":"https:\/\/maqcenter.com\/#website","url":"https:\/\/maqcenter.com\/","name":"MAQcenter","description":"El centro de tus soluciones","publisher":{"@id":"https:\/\/maqcenter.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maqcenter.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/maqcenter.com\/#organization","name":"MAQcenter S.A.","url":"https:\/\/maqcenter.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/maqcenter.com\/#\/schema\/logo\/image\/","url":"https:\/\/maqcenter.com\/wp-content\/uploads\/2021\/02\/MAQcenter_logo_vertical.svg","contentUrl":"https:\/\/maqcenter.com\/wp-content\/uploads\/2021\/02\/MAQcenter_logo_vertical.svg","width":300,"height":174,"caption":"MAQcenter S.A."},"image":{"@id":"https:\/\/maqcenter.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/product\/21435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/media\/21436"}],"wp:attachment":[{"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=21435"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=21435"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=21435"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=21435"},{"taxonomy":"marca-producto","embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/marca-producto?post=21435"},{"taxonomy":"serie-producto","embeddable":true,"href":"https:\/\/maqcenter.com\/pt-pt\/wp-json\/wp\/v2\/serie-producto?post=21435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}